{"id":581,"date":"2023-03-21T13:07:06","date_gmt":"2023-03-21T13:07:06","guid":{"rendered":"https:\/\/www.seafarersclaim.com\/?page_id=581"},"modified":"2023-04-11T09:31:15","modified_gmt":"2023-04-11T09:31:15","slug":"id-page-v1-1","status":"publish","type":"page","link":"https:\/\/www.seafarersclaim.com\/fil\/id-page-v1-1\/","title":{"rendered":"id page v1.1"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-581","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.seafarersclaim.com\/fil\/wp-json\/wp\/v2\/pages\/581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seafarersclaim.com\/fil\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.seafarersclaim.com\/fil\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.seafarersclaim.com\/fil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seafarersclaim.com\/fil\/wp-json\/wp\/v2\/comments?post=581"}],"version-history":[{"count":1,"href":"https:\/\/www.seafarersclaim.com\/fil\/wp-json\/wp\/v2\/pages\/581\/revisions"}],"predecessor-version":[{"id":582,"href":"https:\/\/www.seafarersclaim.com\/fil\/wp-json\/wp\/v2\/pages\/581\/revisions\/582"}],"wp:attachment":[{"href":"https:\/\/www.seafarersclaim.com\/fil\/wp-json\/wp\/v2\/media?parent=581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}